{"id":1605,"date":"2022-12-06T07:39:41","date_gmt":"2022-12-06T07:39:41","guid":{"rendered":"https:\/\/themeforest.vecuro.com\/wordpress\/energiso\/?page_id=1605"},"modified":"2025-09-22T16:52:13","modified_gmt":"2025-09-22T21:52:13","slug":"pricing-plan","status":"publish","type":"page","link":"https:\/\/pagina.teknovus.site\/index.php\/pricing-plan\/","title":{"rendered":"Pricing Plan"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1605\" class=\"elementor elementor-1605\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16a367c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"16a367c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c144aaf\" data-id=\"c144aaf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-70f390b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"70f390b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b4e0d61\" data-id=\"b4e0d61\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-061a9b8 elementor-widget elementor-widget-energisopricingtable\" data-id=\"061a9b8\" data-element_type=\"widget\" data-widget_type=\"energisopricingtable.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pricing-wrapper\"><div class=\"container\"><div class=\"row vs-carousel\" data-slick-arrows=\"true\" data-slick-arrows-1500=\"true\" data-slick-arrows-1200=\"true\" data-slick-arrows-991=\"true\" data-slick-arrows-767=\"true\" data-slick-arrows-575=\"true\" data-slick-dots=\"true\" data-slick-autoplay=\"true\" data-autoplay-speed=\"6000\" data-slide-to-show=\"3\" data-slide-to-show-1500=\"4\" data-slide-to-show-1200=\"3\" data-slide-to-show-991=\"2\" data-slide-to-show-767=\"2\" data-slide-to-show-575=\"1\"><div class=\"col-xl-4\"><div class=\"package-style1\"><div class=\"package-head\"><div class=\"package-img\" data-bg-src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2023\/01\/price-img-1-1.jpg\" data-overlay><\/div><div class=\"package-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2023\/01\/price-1-1.png\" alt=\"price 1 1\"  \/><\/div><h3 class=\"package-name h4\">Fossil Service<\/h3><p class=\"package-text\">Black Panels + 5.12kWhStorage<\/p><p class=\"package-price h1\"><span class=\"currency\">$<\/span>4,100<\/p><\/div><div class=\"package-body\"><div class=\"package-list\"><ul class=\"list-unstyled\">\n                                    <li><i class=\"far fa-check\"><\/i>50 Years Warranty<\/li>\n                                    <li><i class=\"far fa-check\"><\/i>Fully scalable system.<\/li>\n                                    <li><i class=\"far fa-check\"><\/i>Installation<\/li>\n                                    <li><i class=\"far fa-check\"><\/i>Repair &amp; Replacement<\/li>\n                                    <li><i class=\"far fa-check\"><\/i>Skilled Support<\/li>\n                                <\/ul><\/div><p class=\"package-number\">We\u2019ll even pay for your call: <a href=\"tel:+11234562228\">+1 123 456 2228<\/a><\/p><a href=\"https:\/\/wordpress.vecurosoft.com\/energiso\/contact\/\" class=\"vs-btn style2\">Select a Plan<\/a><\/div><div class=\"shape-dotted\"><\/div><\/div><\/div><div class=\"col-xl-4\"><div class=\"package-style1\"><div class=\"package-head\"><div class=\"package-img\" data-bg-src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2023\/01\/price-img-1-2.png\" data-overlay><\/div><div class=\"package-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2023\/01\/price-1-2.png\" alt=\"price 1 2\"  \/><\/div><h3 class=\"package-name h4\">Solar Panel<\/h3><p class=\"package-text\">Black Panels + 5.12kWhStorage<\/p><p class=\"package-price h1\"><span class=\"currency\">$<\/span>2900<\/p><\/div><div class=\"package-body\"><div class=\"package-list\"><ul class=\"list-unstyled\"><li><i class=\"far fa-check\"><\/i>30 Years Warranty<\/li><li><i class=\"far fa-check\"><\/i>Fully scalable system.<\/li><li><i class=\"far fa-check\"><\/i>Installation<\/li><li><i class=\"far fa-check\"><\/i>Repair &amp; Replacement<\/li><li><i class=\"far fa-check\"><\/i>Skilled Support<\/li><\/ul><\/div><p class=\"package-number\">We\u2019ll even pay for your call: <a href=\"tel:+11234562228\">+1 123 456 2228<\/a><\/p><a href=\"https:\/\/wordpress.vecurosoft.com\/energiso\/contact\/\" class=\"vs-btn style2\">Select a Plan<\/a><\/div><div class=\"shape-dotted\"><\/div><\/div><\/div><div class=\"col-xl-4\"><div class=\"package-style1\"><div class=\"package-head\"><div class=\"package-img\" data-bg-src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2023\/01\/price-img-1-3.png\" data-overlay><\/div><div class=\"package-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2023\/01\/price-1-3.png\" alt=\"price 1 3\"  \/><\/div><h3 class=\"package-name h4\">Windmill<\/h3><p class=\"package-text\">Black Panels + 5.12kWhStorage<\/p><p class=\"package-price h1\"><span class=\"currency\">$<\/span>2100<\/p><\/div><div class=\"package-body\"><div class=\"package-list\"><ul class=\"list-unstyled\"><li><i class=\"far fa-check\"><\/i>44 Years Warranty<\/li><li><i class=\"far fa-check\"><\/i>Fully scalable system.<\/li><li><i class=\"far fa-check\"><\/i>Installation<\/li><li><i class=\"far fa-check\"><\/i>Repair &amp; Replacement<\/li><li><i class=\"far fa-check\"><\/i>Skilled Support<\/li><\/ul><\/div><p class=\"package-number\">We\u2019ll even pay for your call: <a href=\"tel:+11234562228\">+1 123 456 2228<\/a><\/p><a href=\"https:\/\/wordpress.vecurosoft.com\/energiso\/contact\/\" class=\"vs-btn style2\">Select a Plan<\/a><\/div><div class=\"shape-dotted\"><\/div><\/div><\/div><div class=\"col-xl-4\"><div class=\"package-style1\"><div class=\"package-head\"><div class=\"package-img\" data-bg-src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2023\/01\/price-img-1-4.png\" data-overlay><\/div><div class=\"package-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2023\/01\/price-1-4.png\" alt=\"price 1 4\"  \/><\/div><h3 class=\"package-name h4\">Global Energy<\/h3><p class=\"package-text\">Black Panels + 5.12kWhStorage<\/p><p class=\"package-price h1\"><span class=\"currency\">$<\/span>5400<\/p><\/div><div class=\"package-body\"><div class=\"package-list\"><ul class=\"list-unstyled\"><li><i class=\"far fa-check\"><\/i>40 Years Warranty<\/li><li><i class=\"far fa-check\"><\/i>Fully scalable system.<\/li><li><i class=\"far fa-check\"><\/i>Installation<\/li><li><i class=\"far fa-check\"><\/i>Repair &amp; Replacement<\/li><li><i class=\"far fa-check\"><\/i>Skilled Support<\/li><\/ul><\/div><p class=\"package-number\">We\u2019ll even pay for your call: <a href=\"tel:+11234562228\">+1 123 456 2228<\/a><\/p><a href=\"https:\/\/wordpress.vecurosoft.com\/energiso\/contact\/\" class=\"vs-btn style2\">Select a Plan<\/a><\/div><div class=\"shape-dotted\"><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0fdf27 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d0fdf27\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9a003a\" data-id=\"e9a003a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-747f4c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"747f4c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-858dec3\" data-id=\"858dec3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41deb56 elementor-widget elementor-widget-energisosectiontitle\" data-id=\"41deb56\" data-element_type=\"widget\" data-widget_type=\"energisosectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<br \/>\n<b>Warning<\/b>:  Undefined array key \"section_title_align\" in <b>\/www\/wwwroot\/pagina.teknovus.site\/wp-content\/plugins\/energiso-core\/addons\/widgets\/section-title.php<\/b> on line <b>355<\/b><br \/>\n<!-- Section Title --><div class=\"title-area\" ><h2 class=\"sec-subtitle subtitle-selector\">WHY YOU CHOOSE US<\/h2><h3 class=\"sec-title title-selector h1\">Award-winning renewable energy solutions<\/h3><\/div><!-- End Section Title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7218376 elementor-widget elementor-widget-energisoprogressbar\" data-id=\"7218376\" data-element_type=\"widget\" data-widget_type=\"energisoprogressbar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"progress-bar-wrapper\"><div class=\"progress-box \"><h3 class=\"progress-box__title\">Wind Turbines<\/h3><span class=\"progress-box__number\">85%<\/span><div class=\"progress-box__progress\"><div class=\"progress-box__bar\" role=\"progressbar\" style=\"width: 85%\" aria-valuenow=\"85\" aria-valuemin=\"0\" aria-valuemax=\"100\"><\/div><\/div><\/div><div class=\"progress-box \"><h3 class=\"progress-box__title\">Hybrid Energy<\/h3><span class=\"progress-box__number\">62%<\/span><div class=\"progress-box__progress\"><div class=\"progress-box__bar\" role=\"progressbar\" style=\"width: 62%\" aria-valuenow=\"62\" aria-valuemin=\"0\" aria-valuemax=\"100\"><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57b080c elementor-widget elementor-widget-energisoimagebox\" data-id=\"57b080c\" data-element_type=\"widget\" data-widget_type=\"energisoimagebox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"img-box2\"><div class=\"img-1\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2023\/01\/why-choose-1.jpg\" alt=\"why choose 1\"  \/><\/div><div class=\"shape-dotted\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bc67bb3\" data-id=\"bc67bb3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-084e73c elementor-widget elementor-widget-text-editor\" data-id=\"084e73c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ut tellus dolor, dapibus eget, elementum vel, ifend cursus el ifen elit. Aenea ifendn auctor wisi et ur na. Aliquam er at volifenutpat tuifendrpis. Ut tuellus dolor, dapibus eget, dolor, dapibus eifeng et, elementum vel,<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60e687a elementor-widget elementor-widget-energisoaboutmedia\" data-id=\"60e687a\" data-element_type=\"widget\" data-widget_type=\"energisoaboutmedia.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"about-media-wrapper\"><div class=\"vs-media about-media \"><div class=\"media-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/10\/why-choose-1.png\" alt=\"why choose 1\"  \/><\/div><div class=\"media-body\"><span class=\"media-title h5\">Award winning team<\/span><p class=\"media-info\">Ut tellus dolor, dapibus eget, elementum vel, ifend cursus eleifend, elit.<\/p><\/div><\/div><div class=\"vs-media about-media \"><div class=\"media-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/10\/why-choose-2.png\" alt=\"why choose 2\"  \/><\/div><div class=\"media-body\"><span class=\"media-title h5\">Money Back Guarantee<\/span><p class=\"media-info\">Ut tellus dolor, dapibus eget, elementum vel, ifend cursus eleifend, elit.<\/p><\/div><\/div><div class=\"vs-media about-media \"><div class=\"media-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/10\/why-choose-3.png\" alt=\"why choose 3\"  \/><\/div><div class=\"media-body\"><span class=\"media-title h5\">Easy Installation<\/span><p class=\"media-info\">Ut tellus dolor, dapibus eget, elementum vel, ifend cursus eleifend, elit.<\/p><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae22b19 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ae22b19\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b557543\" data-id=\"b557543\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b138395 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b138395\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8884651\" data-id=\"8884651\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99667b4 elementor-widget elementor-widget-energisosectiontitle\" data-id=\"99667b4\" data-element_type=\"widget\" data-widget_type=\"energisosectiontitle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Section Title --><div class=\"title-area center\" ><svg class=\"sec-icon\" width=\"68\" height=\"67\" viewBox=\"0 0 68 67\"><path class=\"sec-shape\" d=\"M926,1225l63-39-21-1,26-27-58,35,21,1\" transform=\"translate(-926 -1158)\"><\/path><\/svg><h2 class=\"sec-subtitle subtitle-selector\">PRICING PLAN FOR YOU<\/h2><h3 class=\"sec-title title-selector h1\">Pricing Packages<\/h3><\/div><!-- End Section Title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e06cdf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3e06cdf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-83ea63d\" data-id=\"83ea63d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fde13a elementor-widget elementor-widget-energisopricingtable\" data-id=\"6fde13a\" data-element_type=\"widget\" data-widget_type=\"energisopricingtable.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pricing-wrapper\"><div class=\"container\"><div class=\"row vs-carousel\" data-slick-arrows=\"true\" data-slick-arrows-1500=\"true\" data-slick-arrows-1200=\"true\" data-slick-arrows-991=\"true\" data-slick-arrows-767=\"true\" data-slick-arrows-575=\"true\" data-slick-dots=\"true\" data-slick-autoplay=\"true\" data-autoplay-speed=\"6000\" data-slide-to-show=\"4\" data-slide-to-show-1500=\"4\" data-slide-to-show-1200=\"3\" data-slide-to-show-991=\"2\" data-slide-to-show-767=\"2\" data-slide-to-show-575=\"1\"><div class=\"col-xl-3\"><div class=\"package-style2\"><h3 class=\"package-name\">Solar Panels<\/h3><span class=\"package-label\">5.12kWh Storage<\/span><div class=\"package-price\"><span class=\"currency\">$<\/span>510<\/div><div class=\"package-img\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/pack-1-1.jpg\" alt=\"pack 1 1\"  \/><\/div><p class=\"package-text\">12 Year Product &amp; 25 Year Performance Warranty<\/p><a href=\"https:\/\/wordpress.vecurosoft.com\/energiso\/contact\/\" class=\"vs-btn style2\">Select A Plan<\/a><\/div><\/div><div class=\"col-xl-3\"><div class=\"package-style2\"><h3 class=\"package-name\">Windmill<\/h3><span class=\"package-label\">4.99kWh Storage<\/span><div class=\"package-price\"><span class=\"currency\">$<\/span>840<\/div><div class=\"package-img\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/pack-1-2.jpg\" alt=\"pack 1 2\"  \/><\/div><p class=\"package-text\">12 Year Product &amp; 25 Year Performance Warranty<\/p><a href=\"https:\/\/wordpress.vecurosoft.com\/energiso\/contact\/\" class=\"vs-btn style2\">Select A Plan<\/a><\/div><\/div><div class=\"col-xl-3\"><div class=\"package-style2\"><h3 class=\"package-name\">Global Energy<\/h3><span class=\"package-label\">45.45kWh Storage<\/span><div class=\"package-price\"><span class=\"currency\">$<\/span>1,100<\/div><div class=\"package-img\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/pack-1-3.jpg\" alt=\"pack 1 3\"  \/><\/div><p class=\"package-text\">12 Year Product &amp; 25 Year Performance Warranty<\/p><a href=\"https:\/\/wordpress.vecurosoft.com\/energiso\/contact\/\" class=\"vs-btn style2\">Select A Plan<\/a><\/div><\/div><div class=\"col-xl-3\"><div class=\"package-style2\"><h3 class=\"package-name\">Sun Energy<\/h3><span class=\"package-label\">12.20kWh Storage<\/span><div class=\"package-price\"><span class=\"currency\">$<\/span>1,690<\/div><div class=\"package-img\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/pack-1-4.jpg\" alt=\"pack 1 4\"  \/><\/div><p class=\"package-text\">12 Year Product &amp; 25 Year Performance Warranty<\/p><a href=\"https:\/\/wordpress.vecurosoft.com\/energiso\/contact\/\" class=\"vs-btn style2\">Select A Plan<\/a><\/div><\/div><div class=\"col-xl-3\"><div class=\"package-style2\"><h3 class=\"package-name\">Fossil Panels<\/h3><span class=\"package-label\">78.10kWh Storage<\/span><div class=\"package-price\"><span class=\"currency\">$<\/span>1,690<\/div><div class=\"package-img\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/pack-1-5.jpg\" alt=\"pack 1 5\"  \/><\/div><p class=\"package-text\">12 Year Product &amp; 25 Year Performance Warranty<\/p><a href=\"https:\/\/wordpress.vecurosoft.com\/energiso\/contact\/\" class=\"vs-btn style2\">Select A Plan<\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-025312e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"025312e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a384c57\" data-id=\"a384c57\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25a5e90 elementor-widget elementor-widget-energisotestimonialslider\" data-id=\"25a5e90\" data-element_type=\"widget\" data-widget_type=\"energisotestimonialslider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"testimonial-wrapper\"><div class=\"container\"><div class=\"position-relative\"><div class=\"row gx-50 align-items-lg-center justify-content-center justify-content-md-start\"><div class=\"col-5 col-md-12 col-lg-2 col-xxl-auto order-1 order-md-1\"><div class=\"testi-nav nav-prev\"><button class=\"tab-btn\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/testi-2-1.jpg\" alt=\"testi 2 1\"  \/><\/button><button class=\"tab-btn\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/testi-2-2.jpg\" alt=\"testi 2 2\"  \/><\/button><button class=\"tab-btn\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/testi-2-3.jpg\" alt=\"testi 2 3\"  \/><\/button><\/div><\/div><div class=\"col-md-12 col-lg-8 col-xxl order-3 order-md-2 mt-4 mt-md-0\"><div class=\"testi-style2\"><div class=\"shape-dotted jump-reverse\"><\/div><div id=\"testislide2\"><div class=\"slide-1\"><div class=\"testi-body\"><div class=\"testi-img\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/testi-2-1.jpg\" alt=\"testi 2 1\"  \/><\/div><div class=\"media-body\"><div class=\"testi-rating\"><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><\/div><p class=\"testi-text\">\u201cThey were fantastic through the entire purchase process. Had lots of ask and they were patient. When my system arrived\u201d<\/p><h3 class=\"testi-name h4\">Marko Polo<\/h3><span class=\"testi-degi\">PRO SYSTEMS FOUNDER<\/span><\/div><div class=\"quote-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/quote-icon.png\" alt=\"quote icon\"  \/><\/div><\/div><\/div><div class=\"slide-2\"><div class=\"testi-body\"><div class=\"testi-img\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/testi-2-2.jpg\" alt=\"testi 2 2\"  \/><\/div><div class=\"media-body\"><div class=\"testi-rating\"><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><\/div><p class=\"testi-text\">\u201cFrom its medieval origins to the digital era, learn everything there is to know about the ubiquitous lorem ipsum dummy.\u201d<\/p><h3 class=\"testi-name h4\">Peter Parker<\/h3><span class=\"testi-degi\">SYSTEMS Developer<\/span><\/div><div class=\"quote-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/quote-icon.png\" alt=\"quote icon\"  \/><\/div><\/div><\/div><div class=\"slide-3\"><div class=\"testi-body\"><div class=\"testi-img\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/testi-2-3.jpg\" alt=\"testi 2 3\"  \/><\/div><div class=\"media-body\"><div class=\"testi-rating\"><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><i class=\"fa fa-star\"><\/i><\/div><p class=\"testi-text\">\u201cChewck were fantastic through the entire purchase process. Had lots of ask and they were patient. When my system Jonge\u201d<\/p><h3 class=\"testi-name h4\">Vivi Marian<\/h3><span class=\"testi-degi\">Solar System Expert<\/span><\/div><div class=\"quote-icon\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/quote-icon.png\" alt=\"quote icon\"  \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"col-5 col-md-12 col-lg-2 col-xxl-auto order-2 order-md-3\"><div class=\"testi-nav nav-next\"><button class=\"tab-btn\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/testi-2-1.jpg\" alt=\"testi 2 1\"  \/><\/button><button class=\"tab-btn\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/testi-2-2.jpg\" alt=\"testi 2 2\"  \/><\/button><button class=\"tab-btn\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/testi-2-3.jpg\" alt=\"testi 2 3\"  \/><\/button><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40e3908 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"40e3908\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f04a28\" data-id=\"8f04a28\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9d012aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9d012aa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8268af2\" data-id=\"8268af2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66750af elementor-widget elementor-widget-text-editor\" data-id=\"66750af\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<span class=\"sec-subtitle text-decoration-underline mb-4 pb-lg-3 text-center\">Client and sponsor<\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-799de93 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"799de93\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f63ca7d\" data-id=\"f63ca7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4328a99 elementor-widget elementor-widget-energisobrandimage\" data-id=\"4328a99\" data-element_type=\"widget\" data-widget_type=\"energisobrandimage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"brand-image-wrapper\"><div class=\"container\"><div class=\"row vs-carousel\" data-slide-to-show=\"5\" data-slick-autoplay=\"true\"><div class=\"col-xl-4\"><div class=\"brand-style1\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/brand-1-1.png\" alt=\"brand 1 1\"  \/><\/div><\/div><div class=\"col-xl-4\"><div class=\"brand-style1\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/brand-1-2.png\" alt=\"brand 1 2\"  \/><\/div><\/div><div class=\"col-xl-4\"><div class=\"brand-style1\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/brand-1-3.png\" alt=\"brand 1 3\"  \/><\/div><\/div><div class=\"col-xl-4\"><div class=\"brand-style1\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/brand-1-4.png\" alt=\"brand 1 4\"  \/><\/div><\/div><div class=\"col-xl-4\"><div class=\"brand-style1\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/brand-1-5.png\" alt=\"brand 1 5\"  \/><\/div><\/div><div class=\"col-xl-4\"><div class=\"brand-style1\"><img decoding=\"async\" src=\"https:\/\/wordpress.vecurosoft.com\/energiso\/wp-content\/uploads\/2022\/11\/brand-1-6.png\" alt=\"brand 1 6\"  \/><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fossil Service Black Panels + 5.12kWhStorage $4,100 50 Years Warranty Fully scalable system. Installation Repair &amp; Replacement Skilled Support We\u2019ll even pay for your call: +1 123 456 2228 Select a Plan Solar Panel Black Panels + 5.12kWhStorage $2900 30 Years Warranty Fully scalable system. Installation Repair &amp; Replacement Skilled Support We\u2019ll even pay for&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-builder.php","meta":{"footnotes":""},"class_list":["post-1605","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/pagina.teknovus.site\/index.php\/wp-json\/wp\/v2\/pages\/1605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pagina.teknovus.site\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pagina.teknovus.site\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pagina.teknovus.site\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pagina.teknovus.site\/index.php\/wp-json\/wp\/v2\/comments?post=1605"}],"version-history":[{"count":1,"href":"https:\/\/pagina.teknovus.site\/index.php\/wp-json\/wp\/v2\/pages\/1605\/revisions"}],"predecessor-version":[{"id":2640,"href":"https:\/\/pagina.teknovus.site\/index.php\/wp-json\/wp\/v2\/pages\/1605\/revisions\/2640"}],"wp:attachment":[{"href":"https:\/\/pagina.teknovus.site\/index.php\/wp-json\/wp\/v2\/media?parent=1605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}